{"id":1310,"date":"2025-04-14T08:09:12","date_gmt":"2025-04-14T08:09:12","guid":{"rendered":"https:\/\/kurabotanica.com\/sin-categoria\/licor-blue-curacao\/"},"modified":"2025-04-22T11:34:55","modified_gmt":"2025-04-22T11:34:55","slug":"licor-blue-curacao","status":"publish","type":"post","link":"https:\/\/kurabotanica.com\/es\/curacao-es\/licor-blue-curacao\/","title":{"rendered":"Licor Blue Curacao"},"content":{"rendered":"<p>Cuando piensa en Curacao, probablemente le viene inmediatamente a la mente esa imagen caribe\u00f1a, con palmeras meci\u00e9ndose y mar cristalino. Pero, por supuesto, \u00a1tambi\u00e9n un delicioso c\u00f3ctel! Cuando la gente de todo el mundo busca Curacao en Google, no tarda en toparse con preciosas fotos del Blue Cura\u00e7ao, \u00a1el c\u00f3ctel m\u00e1s famoso de la isla!<\/p>\n<p>El licor Blue Curacao es una de las bebidas espirituosas m\u00e1s populares y vers\u00e1tiles. Se trata de un licor dulce con sabor a c\u00edtricos elaborado a partir de las c\u00e1scaras secas del c\u00edtrico laraha. El sabor y el color \u00fanicos del Curacao Azul se han convertido en las \u00faltimas d\u00e9cadas en un ingrediente habitual de muchos c\u00f3cteles deliciosos. De hecho, confiere un tono azul vibrante a las bebidas y realza su sabor.<\/p>\n<p>A pesar de su popularidad, poca gente sabe mucho sobre este licor o de d\u00f3nde procede. Le contaremos la historia y el proceso de producci\u00f3n de Blue Curacao. Y por supuesto sobre las recetas de c\u00f3cteles m\u00e1s famosas que puedes preparar en el Taller de C\u00f3cteles de Chobolobo\u2026.<\/p>\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"Cura\u00e7ao Liqueur Distillery Tour at Landhuis Chobolobo\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/SRoBumj6pzI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<h2>Historia de Blue Curacao<\/h2>\n<p>Los or\u00edgenes del Curacao Azul se remontan a la Espa\u00f1a del siglo XV. Los colonos descubrieron que remojando c\u00e1scaras de naranja secas en alcohol se obten\u00eda una bebida de sabor agradable (licor de naranja). Este descubrimiento se extendi\u00f3 r\u00e1pidamente por Europa y lleg\u00f3 a la isla holandesa de Curacao en 1634. Aqu\u00ed, fue perfeccionado por la destiler\u00eda local. Para ello se utiliz\u00f3 la mencionada fruta laraha, com\u00fan en la regi\u00f3n.<\/p>\n<p>Con el tiempo, se fueron a\u00f1adiendo diferentes sabores hasta que el Blue Curacao vio la luz en 1896. Senior &amp; Co, una de las destiler\u00edas m\u00e1s antiguas de la isla, desarroll\u00f3 su receta original con colorante alimentario para darle su distintivo tono azul. Desde entonces, Blue Curacao se ha convertido en uno de los licores m\u00e1s populares del mundo y puede encontrarse en bares de todo el planeta, desde Nueva York a Londres, pasando por Tokio.<\/p>\n<h2>Proceso de producci\u00f3n del Curacao Azul<\/h2>\n<p>\u00bfC\u00f3mo se prepara este delicioso licor? El Curacao Azul se elabora mediante un largo proceso de varias etapas:<\/p>\n<h3>Recogida<\/h3>\n<p>El primer paso consiste en recolectar laraha madura de los \u00e1rboles que crecen en las colinas cercanas al nivel del mar por toda Curacao.<\/p>\n<h3>Peeling<\/h3>\n<p>A continuaci\u00f3n, los frutos recolectados se pelan a mano y se colocan en salmuera durante toda la noche.<\/p>\n<h3>Seco<\/h3>\n<p>Despu\u00e9s de remojarlas, se colocan sobre bastidores a la luz directa del sol para que se sequen durante quince d\u00edas.<\/p>\n<h3>Extracci\u00f3n de<\/h3>\n<p>Tras el secado, un proceso de extracci\u00f3n de aceite extrae los aceites esenciales que forman un l\u00edquido de color anaranjado (llamado saccharum).<\/p>\n<h3>Destilaci\u00f3n<\/h3>\n<p>A continuaci\u00f3n, este l\u00edquido se destila en alcohol, que se mezcla con jarabe de az\u00facar y se filtra varias veces.<\/p>\n<h3>Sabor\/Color<\/h3>\n<p>Por \u00faltimo, se pueden a\u00f1adir aromatizantes naturales como vainas de vainilla o especias como la canela. Esto se hace junto con tintes para crear diferentes tipos, como el Curacao verde o el azul.<\/p>\n<h3>Embotellado\/Etiquetado<\/h3>\n<p>Una vez completados todos estos pasos, el producto est\u00e1 listo para ser embotellado y etiquetado para su venta en todo el mundo.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-558 aligncenter\" src=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/chobolobo-landhuis-1-600x400.webp\" alt=\"chobolobo landhuis 1\" width=\"600\" height=\"400\" srcset=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/chobolobo-landhuis-1-600x400.webp 600w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/chobolobo-landhuis-1-768x512.webp 768w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/chobolobo-landhuis-1.webp 1200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2>Casa rural Chobolobo<\/h2>\n<p>\u00bfD\u00f3nde se fabrican todas estas golosinas? Localmente, se hace en la destiler\u00eda de Country House Chobolobo. Con sede en Curacao, produce este sabor \u00fanico desde 1929. Adem\u00e1s del Curacao Azul, tambi\u00e9n se elaboran otros licores de vivos colores. Mientras tanto, \u00e9stas se elaboran con sirope dulce (en lugar de colorante alimentario) y las bebidas maduran durante varias semanas en barricas de roble antes de ser embotelladas.<\/p>\n<p>En Country House Chobolobo, la calidad es primordial. Todos los ingredientes utilizados en sus productos proceden de agricultores locales que cumplen estrictas normas de control de calidad. El compromiso de Landhuis Chobolobo con la excelencia garantiza que cada botella de Blue Curacao contenga \u00fanicamente sabores puros.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-561 aligncenter\" src=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo-710x400.webp\" alt=\"landhuis chobolobo\" width=\"710\" height=\"400\" srcset=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo-710x400.webp 710w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo-1400x788.webp 1400w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo-768x432.webp 768w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo-1536x865.webp 1536w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/landhuis-chobolobo.webp 1920w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/><\/p>\n<h3>Excursi\u00f3n a Chobolobo<\/h3>\n<p>Si busca una aut\u00e9ntica experiencia caribe\u00f1a, no busque m\u00e1s: Country House Chobolobo. Para los que quieran experimentar algo m\u00e1s que el sabor de Blue Curacao, <a href=\"https:\/\/www.chobolobo.com\/guided-tours\" target=\"_blank\" rel=\"noopener\">Chobolobo<\/a> ofrece <a href=\"https:\/\/www.chobolobo.com\/guided-tours\" target=\"_blank\" rel=\"noopener\">visitas a su destiler\u00eda<\/a>. Durante estas visitas, los visitantes pueden conocer de primera mano el proceso de producci\u00f3n y la historia.<\/p>\n<p>Tambi\u00e9n podr\u00e1 degustar distintos tipos de variedades \u00fanicas que normalmente no est\u00e1n disponibles en las estanter\u00edas de las tiendas. Adem\u00e1s, en Landhuis Chobolobo\u2019s ofrecen una combinaci\u00f3n de platos que se pueden consumir durante la excursi\u00f3n, lo que permite a los hu\u00e9spedes saborear realmente lo que hace tan especial a Blue Curacao.<\/p>\n<h2>Taller de cocteler\u00eda de Chobolobo<\/h2>\n<p>Ahora s\u00ed que es divertido. Tras la visita a la Mansi\u00f3n Chobolobo, contin\u00fae con el Taller de Cocteler\u00eda de Chobolobo. Aprenda a preparar sus propios c\u00f3cteles deliciosos con la ayuda de camareros expertos. Puede crear sus propios c\u00f3cteles exclusivos con Blue Curacao combin\u00e1ndolo, agit\u00e1ndolo y aderez\u00e1ndolo con diferentes y sabrosos sabores. \u00a1Salud!<\/p>\n<p>Sobre todo, no olvides hacer fotos de tus coloridas creaciones. Totalmente divertido para tu Insta y Snapchat. <strong>Todos los viernes a las 14.00, puedes apuntarte al taller de cocteler\u00eda de Chobolobo por 45 $<\/strong>.<\/p>\n<h2>Los c\u00f3cteles m\u00e1s famosos de Blue Curacao<\/h2>\n<p>El Blue Curacao es un ingrediente muy utilizado en muchos c\u00f3cteles cl\u00e1sicos, pero tambi\u00e9n hay recetas menos conocidas que utilizan este delicioso licor de Curacao. Estos son algunos de nuestros favoritos en el Taller de Cocteler\u00eda de Chobolobo:<\/p>\n<h3>Laguna Azul<\/h3>\n<p>Una refrescante mezcla de Blue Curacao, vodka, zumo de pi\u00f1a y zumo de lima, aderezada con limonada (o agua con gas).<\/p>\n<h3>Limonada El\u00e9ctrica<\/h3>\n<p>Una mezcla afrutada de partes iguales de Blue Curacao, vodka, triple sec y sour mix con mucho hielo y rodajas de lim\u00f3n.<\/p>\n<h3>Brisa de Verano<\/h3>\n<p>Un refresco perfecto para el verano a base de ron blanco, Blue Curacao, zumo de ar\u00e1ndanos y zumo de pi\u00f1a con hielo y gajos de lima como guarnici\u00f3n.<\/p>\n<h3>Flamingo<\/h3>\n<p>Una ex\u00f3tica mezcla de ron de coco, amaretto, licor de mel\u00f3n y Blue Curacao, adem\u00e1s de zumo de pi\u00f1a y zumo de lima. Acabado con granadina para el efecto rosa.<\/p>\n<h3>Conclusi\u00f3n licor Blue Curacao<\/h3>\n<p>As\u00ed que podemos afirmar sin temor a equivocarnos que el licor Blue Curacao no s\u00f3lo es incre\u00edblemente vers\u00e1til, sino que tambi\u00e9n tiene una historia milenaria. Hoy en d\u00eda, este licor dulce con sabor a c\u00edtricos sigue siendo popular en los bares de todo el mundo por su capacidad para realzar los sabores de estos c\u00f3cteles tan conocidos y a\u00f1adir un tono azul caribe\u00f1o.<\/p>\n<p>Con su inconfundible perfil de sabor y su vibrante color, es un \u00e9xito en todas las fiestas y happy hours. Tanto si lo bebes solo como si lo mezclas con otras bebidas en sabrosos c\u00f3cteles, lo m\u00e1s probable es que guste a todo el mundo. \u00bfA qu\u00e9 esperas? Pruebe Blue Curacao hoy mismo y deje volar su imaginaci\u00f3n.<\/p>\n<div class=\"row align-middle align-center\"  id=\"row-1159611841\">\n\n\n\t<div id=\"col-757357785\" class=\"col medium-12 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(242, 242, 242);\" >\n\t\t\t\n\t\t\t\n\n<div class=\"row row-collapse align-middle\"  id=\"row-1079397769\">\n\n\n\t<div id=\"col-1753658620\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_974037375\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img decoding=\"async\" width=\"1075\" height=\"650\" src=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/Carousel-Kura-Botanica-2.webp\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/Carousel-Kura-Botanica-2.webp 1075w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/Carousel-Kura-Botanica-2-662x400.webp 662w, https:\/\/kurabotanica.com\/wp-content\/uploads\/2025\/04\/Carousel-Kura-Botanica-2-768x464.webp 768w\" sizes=\"(max-width: 1075px) 100vw, 1075px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_974037375 {\n  width: 100%;\n}\n@media (min-width:850px) {\n  #image_974037375 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2077507499\" class=\"col medium-12 small-12 large-6 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-282526512\" class=\"text\">\n\t\t\n\n<h3>Experimente la esencia de Cura\u00e7ao en Kura Botanica<\/h3>\n\t\t\n<style>\n#text-282526512 {\n  font-size: 1.65rem;\n  line-height: 1.4;\n}\n@media (min-width:550px) {\n  #text-282526512 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1393598255\" class=\"text\">\n\t\t\n\n<p>Repartida en un \u00e1rea de ocho manzanas, esta propiedad ofrece una experiencia de lujo \u00fanica en un refugio bot\u00e1nico y tranquilo, que ofrece total privacidad e intimidad.<\/p>\n\t\t\n<style>\n#text-1393598255 {\n  font-size: 1rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-835166295\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-835166295 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<button data-clock-pms-wbe-button=\"\" class=\"button primary expand\" rel=\"noopener\" style=\"border-radius:99px;padding:0px 0px 0px 20px; font-family:'New Spirit',sans-serif;\">\n<span>Consultar disponibilidad<\/span><\/button>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2077507499 > .col-inner {\n  padding: 20px 7% 20px 7%;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2077507499 > .col-inner {\n    padding: 40px 10% 40px 10%;\n  }\n}\n@media (min-width:850px) {\n  #col-2077507499 > .col-inner {\n    padding: 30px 10% 30px 10%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1159611841 > .col > .col-inner {\n  background-color: rgba(191, 154, 120, 0.2);\n}\n<\/style>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuando piensa en Curacao, probablemente le viene inmediatamente a la mente esa imagen caribe\u00f1a, con palmeras meci\u00e9ndose y mar cristalino. Pero, por supuesto, \u00a1tambi\u00e9n un delicioso c\u00f3ctel! Cuando la gente de todo el mundo busca Curacao en Google, no tarda en toparse con preciosas fotos del Blue Cura\u00e7ao, \u00a1el c\u00f3ctel m\u00e1s famoso de la isla! [&#8230;]\n","protected":false},"author":2,"featured_media":557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curacao-es"],"_links":{"self":[{"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/posts\/1310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/comments?post=1310"}],"version-history":[{"count":0,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/posts\/1310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/media\/557"}],"wp:attachment":[{"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/media?parent=1310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/categories?post=1310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kurabotanica.com\/es\/wp-json\/wp\/v2\/tags?post=1310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}